{"id":932,"date":"2015-06-08T23:29:37","date_gmt":"2015-06-08T21:29:37","guid":{"rendered":"http:\/\/amapdelalys.org\/blog\/?p=932"},"modified":"2017-01-30T23:33:45","modified_gmt":"2017-01-30T22:33:45","slug":"lamap-et-le-forum-ethique","status":"publish","type":"post","link":"https:\/\/amapdelalys.org\/blog\/2015\/06\/lamap-et-le-forum-ethique\/","title":{"rendered":"l&rsquo;amap et le march\u00e9 \u00e9quitable"},"content":{"rendered":"<p>L&rsquo;amap de la Lys a particip\u00e9 au march\u00e9 \u00e9quitable, le journaliste n&rsquo;a pas pris l&rsquo;essentiel du propos et du titre de l&rsquo;association mais bon:<\/p>\n<p><a title=\"http:\/\/www.nordeclair.fr\/info-locale\/halluin-artisans-et-producteurs-locaux-font-leur-marche-ia47b1959n745924\" href=\"http:\/\/www.nordeclair.fr\/info-locale\/halluin-artisans-et-producteurs-locaux-font-leur-marche-ia47b1959n745924\">http:\/\/www.nordeclair.fr\/info-locale\/halluin-artisans-et-producteurs-locaux-font-leur-marche-ia47b1959n745924<\/a><\/p>\n<p>c&rsquo;est d\u00e9j\u00e0 cela<\/p>\n<p>De notre c\u00f4t\u00e9 nous avions pr\u00e9par\u00e9 des jus de l\u00e9gumes et fruits avec des bonbonnes d&rsquo;eau aromatis\u00e9es. Franc succ\u00e8s, notre stand \u00e9tait celui o\u00f9 il y avait le plus de passage.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;amap de la Lys a particip\u00e9 au march\u00e9 \u00e9quitable, le journaliste n&rsquo;a pas pris l&rsquo;essentiel du propos et du titre de l&rsquo;association mais bon: http:\/\/www.nordeclair.fr\/info-locale\/halluin-artisans-et-producteurs-locaux-font-leur-marche-ia47b1959n745924 c&rsquo;est d\u00e9j\u00e0 cela De notre c\u00f4t\u00e9 nous avions pr\u00e9par\u00e9 des jus de l\u00e9gumes et fruits avec des bonbonnes d&rsquo;eau aromatis\u00e9es. Franc succ\u00e8s, notre stand \u00e9tait celui o\u00f9 il y avait [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":"","footnotes":""},"categories":[22],"tags":[],"class_list":["post-932","post","type-post","status-publish","format-standard","hentry","category-articles-de-presse"],"_links":{"self":[{"href":"https:\/\/amapdelalys.org\/blog\/wp-json\/wp\/v2\/posts\/932","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amapdelalys.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amapdelalys.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amapdelalys.org\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amapdelalys.org\/blog\/wp-json\/wp\/v2\/comments?post=932"}],"version-history":[{"count":3,"href":"https:\/\/amapdelalys.org\/blog\/wp-json\/wp\/v2\/posts\/932\/revisions"}],"predecessor-version":[{"id":935,"href":"https:\/\/amapdelalys.org\/blog\/wp-json\/wp\/v2\/posts\/932\/revisions\/935"}],"wp:attachment":[{"href":"https:\/\/amapdelalys.org\/blog\/wp-json\/wp\/v2\/media?parent=932"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amapdelalys.org\/blog\/wp-json\/wp\/v2\/categories?post=932"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amapdelalys.org\/blog\/wp-json\/wp\/v2\/tags?post=932"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}